{"id":3470,"date":"2019-04-10T21:49:36","date_gmt":"2019-04-10T21:49:36","guid":{"rendered":"http:\/\/photographybykaseyduvall.com\/?p=3470"},"modified":"2022-12-31T22:07:17","modified_gmt":"2022-12-31T22:07:17","slug":"baby-girl-sitter-milestone-session-southeast-missouri-photography","status":"publish","type":"post","link":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/","title":{"rendered":"Baby Girl Sitter Milestone Session | Southeast Missouri Photography"},"content":{"rendered":"\n\n\n<p>Baby A is just about as sweet as they come. Sporting her beautiful hair, she sure does light up a room. She has to be one of the giggliest little ones I&#8217;ve been graced with. In the bucket, out of the bucket, smiles all the way. And to top it all off her Momma brought the CUTEST outfits for her. I also had something up my sleeve&#8230; with Easter right around the corner&#8230;. she had to put on the bunny outfit! <\/p>\n\n\n\n<p>Milestone sessions are perfect for every little one. The time passes so quickly.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1319\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-1.jpg?resize=1760%2C1319&#038;quality=89\" alt=\"\" class=\"wp-image-3537\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-1.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-1.jpg?resize=854%2C640&amp;quality=89&amp;ssl=1 854w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-1.jpg?resize=768%2C576&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-1 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3504\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-2.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3504\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-2.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-2.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-2.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-2.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3505\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-3.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3505\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-3.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-3.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-3.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3506\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-4.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3506\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-4.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-4.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-4.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3507\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-5.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3507\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-5.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-5.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-5.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-5.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1760\" data-id=\"3508\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-6.jpg?resize=1760%2C1760&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3508\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-6.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-6.jpg?resize=300%2C300&amp;quality=89&amp;ssl=1 300w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-6.jpg?resize=640%2C640&amp;quality=89&amp;ssl=1 640w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-6.jpg?resize=768%2C768&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3509\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-7.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3509\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-7.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-7.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-7.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"813\" data-id=\"3510\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-8.jpg?resize=1760%2C813&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3510\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-8.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-8.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-8.jpg?resize=768%2C355&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"813\" data-id=\"3515\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-12.jpg?resize=1760%2C813&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3515\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-12.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-12.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-12.jpg?resize=768%2C355&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1321\" data-id=\"3516\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-13.jpg?resize=1760%2C1321&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3516\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-13.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-13.jpg?resize=853%2C640&amp;quality=89&amp;ssl=1 853w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-13.jpg?resize=768%2C576&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3518\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-15.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3518\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-15.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-15.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-15.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3519\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-16.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3519\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-16.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-16.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-16.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-16.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3520\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-17.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3520\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-17.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-17.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-17.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-17.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3521\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-18.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3521\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-18.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-18.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-18.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3522\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-19.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3522\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-19.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-19.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-19.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3523\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-20.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3523\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-20.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-20.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-20.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-20.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3524\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-21.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3524\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-21.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-21.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-21.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-21.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"587\" data-id=\"3525\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?resize=1760%2C587&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3525\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?resize=960%2C320&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?resize=768%2C256&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"813\" data-id=\"3529\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-25.jpg?resize=1760%2C813&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3529\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-25.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-25.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-25.jpg?resize=768%2C355&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3530\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-26.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3530\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-26.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-26.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-26.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3531\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-27.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3531\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-27.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-27.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-27.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3532\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-28.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3532\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-28.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-28.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-28.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1173\" data-id=\"3533\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-29.jpg?resize=1760%2C1173&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3533\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-29.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-29.jpg?resize=960%2C640&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-29.jpg?resize=768%2C512&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-29.jpg?resize=1472%2C982&amp;quality=89&amp;ssl=1 1472w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3534\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-30.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3534\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-30.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-30.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-30.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"812\" data-id=\"3536\" src=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-32.jpg?resize=1760%2C812&#038;quality=89&#038;ssl=1\" alt=\"\" class=\"wp-image-3536\" srcset=\"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-32.jpg?w=1760&amp;quality=89&amp;ssl=1 1760w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-32.jpg?resize=960%2C443&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-32.jpg?resize=768%2C354&amp;quality=89&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Photography by Kasey Duvall is located in Southeast, Missouri. Our  studio is located in the beautiful town of Perryville, Missouri. We  offer family, maternity, newborn, senior, and milestone baby sessions as  well as packages for bump to baby. Photography by Kasey Duvall is  Southeast, Missouri\u2019s premier maternity, newborn, and baby photographer.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Photography by Kasey Duvall serves Perryville as well as other \nSoutheast, Missouri areas including Ste. Genevieve, Altenburg, Jackson, \nCape Girardeau, Fredericktown, Farmington, Patton, Marble Hill, Scott \nCity, Kelso and surrounding areas.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Baby A is just about as sweet as they come. Sporting her beautiful hair, she sure does light up a room. She has to be one of the giggliest little ones I&#8217;ve been graced with. In the bucket, out of the bucket, smiles all the way. And to top it all off her Momma brought [&hellip;]<\/p>\n<div class=\"view-post\"><a class=\"view_post_button\" href=\"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/\"><\/p>\n<h3>View Post<\/h3>\n<p><\/a><\/<div class=\"view-post\"><a class=\"view_post_button\" href=\"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/\"><h3>View Post<\/h3><\/a><\/div>","protected":false},"author":2,"featured_media":3525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,15,31,1],"tags":[34,30,36,6,32,28,27,9],"class_list":{"0":"post-3470","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-children","8":"category-family","9":"category-milestone","10":"category-uncategorized","11":"tag-milestone","12":"tag-perryville","13":"tag-perryville-photographer","14":"tag-photography-by-kasey-duvall","15":"tag-southeast-missouri","16":"tag-southeast-missouri-child-photographer","17":"tag-southeast-missouri-newborn-photographer","18":"tag-southeast-missouri-photographer","19":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Baby Girl Sitter Milestone Session | Southeast Missouri Photography - Perryville, Missouri Newborn &amp; Family Photographer | Photography by Kasey Duvall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baby Girl Sitter Milestone Session | Southeast Missouri Photography\" \/>\n<meta property=\"og:description\" content=\"Baby A is just about as sweet as they come. Sporting her beautiful hair, she sure does light up a room. She has to be one of the giggliest little ones I&#8217;ve been graced with. In the bucket, out of the bucket, smiles all the way. And to top it all off her Momma brought [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/\" \/>\n<meta property=\"og:site_name\" content=\"Perryville, Missouri Newborn &amp; Family Photographer | Photography by Kasey Duvall\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/photographybykaseyduvall\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-10T21:49:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-31T22:07:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1760\" \/>\n\t<meta property=\"og:image:height\" content=\"587\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin@photographybykaseyduvall.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin@photographybykaseyduvall.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/\"},\"author\":{\"name\":\"admin@photographybykaseyduvall.com\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/4925e7bbe1c1a2ddd4b5ce07f45948c2\"},\"headline\":\"Baby Girl Sitter Milestone Session | Southeast Missouri Photography\",\"datePublished\":\"2019-04-10T21:49:36+00:00\",\"dateModified\":\"2022-12-31T22:07:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/photographybykaseyduvall.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1\",\"keywords\":[\"milestone\",\"perryville\",\"perryville photographer\",\"photography by kasey duvall\",\"southeast missouri\",\"southeast missouri child photographer\",\"southeast missouri newborn photographer\",\"southeast missouri photographer\"],\"articleSection\":[\"Children\",\"Family\",\"Milestone\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/\",\"url\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/\",\"name\":\"Baby Girl Sitter Milestone Session | Southeast Missouri Photography - Perryville, Missouri Newborn &amp; Family Photographer | Photography by Kasey Duvall\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/photographybykaseyduvall.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1\",\"datePublished\":\"2019-04-10T21:49:36+00:00\",\"dateModified\":\"2022-12-31T22:07:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/photographybykaseyduvall.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/photographybykaseyduvall.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1\",\"width\":1760,\"height\":587},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/2019\\\/04\\\/baby-girl-sitter-milestone-session-southeast-missouri-photography\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baby Girl Sitter Milestone Session | Southeast Missouri Photography\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/\",\"name\":\"Perryville, Missouri Newborn & Family Photographer | Photography by Kasey Duvall\",\"description\":\"Missouri Newborn &amp; Family Photographer\",\"publisher\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#organization\",\"name\":\"Photography by Kasey Duvall\",\"url\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/photographybykaseyduvall.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/cropped-logo%402x.png?fit=700%2C294&quality=80&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/photographybykaseyduvall.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/cropped-logo%402x.png?fit=700%2C294&quality=80&ssl=1\",\"width\":700,\"height\":294,\"caption\":\"Photography by Kasey Duvall\"},\"image\":{\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/photographybykaseyduvall\",\"https:\\\/\\\/www.instagram.com\\\/photographybykaseyduvall\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/4925e7bbe1c1a2ddd4b5ce07f45948c2\",\"name\":\"admin@photographybykaseyduvall.com\",\"url\":\"https:\\\/\\\/photographybykaseyduvall.com\\\/wordpress\\\/author\\\/adminphotographybykaseyduvall-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baby Girl Sitter Milestone Session | Southeast Missouri Photography - Perryville, Missouri Newborn &amp; Family Photographer | Photography by Kasey Duvall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/","og_locale":"en_US","og_type":"article","og_title":"Baby Girl Sitter Milestone Session | Southeast Missouri Photography","og_description":"Baby A is just about as sweet as they come. Sporting her beautiful hair, she sure does light up a room. She has to be one of the giggliest little ones I&#8217;ve been graced with. In the bucket, out of the bucket, smiles all the way. And to top it all off her Momma brought [&hellip;]","og_url":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/","og_site_name":"Perryville, Missouri Newborn &amp; Family Photographer | Photography by Kasey Duvall","article_publisher":"https:\/\/www.facebook.com\/photographybykaseyduvall","article_published_time":"2019-04-10T21:49:36+00:00","article_modified_time":"2022-12-31T22:07:17+00:00","og_image":[{"width":1760,"height":587,"url":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg","type":"image\/jpeg"}],"author":"admin@photographybykaseyduvall.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin@photographybykaseyduvall.com","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#article","isPartOf":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/"},"author":{"name":"admin@photographybykaseyduvall.com","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#\/schema\/person\/4925e7bbe1c1a2ddd4b5ce07f45948c2"},"headline":"Baby Girl Sitter Milestone Session | Southeast Missouri Photography","datePublished":"2019-04-10T21:49:36+00:00","dateModified":"2022-12-31T22:07:17+00:00","mainEntityOfPage":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#organization"},"image":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1","keywords":["milestone","perryville","perryville photographer","photography by kasey duvall","southeast missouri","southeast missouri child photographer","southeast missouri newborn photographer","southeast missouri photographer"],"articleSection":["Children","Family","Milestone"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/","url":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/","name":"Baby Girl Sitter Milestone Session | Southeast Missouri Photography - Perryville, Missouri Newborn &amp; Family Photographer | Photography by Kasey Duvall","isPartOf":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#primaryimage"},"image":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1","datePublished":"2019-04-10T21:49:36+00:00","dateModified":"2022-12-31T22:07:17+00:00","breadcrumb":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#primaryimage","url":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1","contentUrl":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1","width":1760,"height":587},{"@type":"BreadcrumbList","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/2019\/04\/baby-girl-sitter-milestone-session-southeast-missouri-photography\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/photographybykaseyduvall.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Baby Girl Sitter Milestone Session | Southeast Missouri Photography"}]},{"@type":"WebSite","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#website","url":"https:\/\/photographybykaseyduvall.com\/wordpress\/","name":"Perryville, Missouri Newborn & Family Photographer | Photography by Kasey Duvall","description":"Missouri Newborn &amp; Family Photographer","publisher":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/photographybykaseyduvall.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#organization","name":"Photography by Kasey Duvall","url":"https:\/\/photographybykaseyduvall.com\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2017\/02\/cropped-logo%402x.png?fit=700%2C294&quality=80&ssl=1","contentUrl":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2017\/02\/cropped-logo%402x.png?fit=700%2C294&quality=80&ssl=1","width":700,"height":294,"caption":"Photography by Kasey Duvall"},"image":{"@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/photographybykaseyduvall","https:\/\/www.instagram.com\/photographybykaseyduvall\/"]},{"@type":"Person","@id":"https:\/\/photographybykaseyduvall.com\/wordpress\/#\/schema\/person\/4925e7bbe1c1a2ddd4b5ce07f45948c2","name":"admin@photographybykaseyduvall.com","url":"https:\/\/photographybykaseyduvall.com\/wordpress\/author\/adminphotographybykaseyduvall-com\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/photographybykaseyduvall.com\/wordpress\/wp-content\/uploads\/2019\/04\/photography-by-kasey-duvall-southeast-missouri-photographer-milestone-sitter-newborn-session-22.jpg?fit=1760%2C587&quality=89&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/posts\/3470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/comments?post=3470"}],"version-history":[{"count":6,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/posts\/3470\/revisions"}],"predecessor-version":[{"id":3787,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/posts\/3470\/revisions\/3787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/media\/3525"}],"wp:attachment":[{"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/media?parent=3470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/categories?post=3470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/photographybykaseyduvall.com\/wordpress\/wp-json\/wp\/v2\/tags?post=3470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}